{"id":3013,"date":"2017-06-09T22:01:36","date_gmt":"2017-06-09T22:01:36","guid":{"rendered":"http:\/\/themes.axilweb.com\/wp\/cynic\/modern-big-digital-agency\/?page_id=6"},"modified":"2017-06-09T22:01:36","modified_gmt":"2017-06-09T22:01:36","slug":"portfolio","status":"publish","type":"page","link":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/portfolio\/","title":{"rendered":"Portfolio"},"content":{"rendered":"<p>[vc_row el_class=&#8221;bg-white portfolio portfolio-content classic-featured-portfolio&#8221;][vc_column]        <h2  class=\"b-clor  \">Featured Projects<\/h2>\n                    <div class=\"row\">\n                                    <div class=\"col-xs-12 col-md-4 col-sm-6\">\n                        <div class=\"box-content-with-img is-featured\"> \n                            <img width=\"360\" height=\"260\" src=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2018\/01\/mobile-app-design-1-360x260.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" loading=\"lazy\" \/>                            <div class=\"box-content-text equalheight\">\n                                                                    <p class=\"gray-text\">\n                                        Featured -  Mobile Apps                                     <\/p>\n                                                                <h3 class=\"semi-bold\">\n                                    <a href=\"#\" data-postid=\"2756\" data-posttype=\"portfolio\" class=\"proDetModal\" data-toggle=\"modal\">Concur<\/a>\n                                <\/h3>\n                                <p>Lorem ipsum dolor sit amet, consect etuer adipi scing elit, sed diam nonum mLorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div><!--end col-xs-12 col-md-4 col-sm-6-->\n                                    <div class=\"col-xs-12 col-md-4 col-sm-6\">\n                        <div class=\"box-content-with-img is-featured\"> \n                            <img width=\"360\" height=\"260\" src=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/website-1-1-1-360x260.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" loading=\"lazy\" \/>                            <div class=\"box-content-text equalheight\">\n                                                                    <p class=\"gray-text\">\n                                        Featured -  Website                                     <\/p>\n                                                                <h3 class=\"semi-bold\">\n                                    <a href=\"#\" data-postid=\"2754\" data-posttype=\"portfolio\" class=\"proDetModal\" data-toggle=\"modal\">Akamai<\/a>\n                                <\/h3>\n                                <p>Lorem ipsum dolor sit amet, consect etuer adipi scing elit, sed diam nonum mLorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div><!--end col-xs-12 col-md-4 col-sm-6-->\n                                    <div class=\"col-xs-12 col-md-4 col-sm-6\">\n                        <div class=\"box-content-with-img is-featured\"> \n                            <img width=\"360\" height=\"260\" src=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/mobile-1-1-360x260.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" loading=\"lazy\" \/>                            <div class=\"box-content-text equalheight\">\n                                                                    <p class=\"gray-text\">\n                                        Featured -  Mobile Apps                                     <\/p>\n                                                                <h3 class=\"semi-bold\">\n                                    <a href=\"#\" data-postid=\"2751\" data-posttype=\"portfolio\" class=\"proDetModal\" data-toggle=\"modal\">Tableau Software<\/a>\n                                <\/h3>\n                                <p>Lorem ipsum dolor sit amet, consect etuer adipi scing elit, sed diam nonum mLorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div><!--end col-xs-12 col-md-4 col-sm-6-->\n                            <\/div><!--row-->\n            [vc_row_inner el_id=&#8221;more-portfolio&#8221; el_class=&#8221;bg-white full-portfolio portfolio classic-portfolio&#8221;][vc_column_inner]        <h2  class=\"b-clor  \">Full Portfolio<\/h2>\n                <div class=\"row\" data-isotope-id=\"#portfolio-940150\">\n            <div class=\"col-xs-12 col-sm-12 col-md-12\">\n                <div class=\"pro-controls\">\n                                            <button class=\"filter active\" data-slug=\"0\" data-filter=\"*\">All Work<\/button>\n                                                <button class=\"filter \" data-slug=\"24\" data-filter=\".logo\">Logo<\/button>\n                                                <button class=\"filter \" data-slug=\"26\" data-filter=\".mobile-apps\">Mobile Apps<\/button>\n                                                <button class=\"filter \" data-slug=\"31\" data-filter=\".social-media\">Social Media<\/button>\n                                                <button class=\"filter \" data-slug=\"33\" data-filter=\".website\">Website<\/button>\n                                        <\/div>\n            <\/div>\n        <\/div><!--row-->\n\n        <div id=\"portfolio-940150\" class=\"port-cat-con row\">\n                            <div class=\"mix logo col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/logo-4-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2753\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix mobile-apps col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/mobile-2-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2741\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix website col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/website-4-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2743\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix mobile-apps col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/mobile-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2751\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix website col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/website-7-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2739\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix logo col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/logo-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2737\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix social-media col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/social-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2736\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix logo col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/logo-2-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2738\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix logo col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/logo-3-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2742\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix logo col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/logo-5-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2757\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix mobile-apps col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2018\/01\/mobile-app-design-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2756\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix social-media col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/social-2-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2740\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix social-media col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/social-3-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2744\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix website col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/website-1-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2754\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                                <div class=\"mix website col-md-4 col-sm-4 col-xs-6\">\n                                            <div class=\"pro-item-img\" data-bg=\"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-content\/uploads\/2017\/06\/website-2-1-1-360x260.jpg\">\n                            <div class=\"por-overley\">\n                                <div class=\"text-inner\">\n                                    <a href=\"javascript:void(0)\" data-type=\"image\" data-postid=\"2745\" data-posttype=\"portfolio\" class=\"btn btn-nofill proDetModal\" data-toggle=\"modal\">VIEW PROJECT<\/a>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                        <!-- End of .video_popup -->\n                                    <\/div>\n\n                        <\/div><!--row-->\n                    <div class=\"row\">\n                <div class=\"col-xs-12\"> <a href=\"#\" data-action=\"cynic_onepage_load_more_portfolio\" data-nonce=\"096e42a7c3\" data-orderby=\"title\" data-order=\"DESC\" data-target=\"#portfolio-940150\" data-page=\"1\" data-pp=\"15\" data-layout=\"classic\" class=\"btn btn-fill load-more-portfolio full-width\">Discover More<\/a> <\/div>\n            <\/div><!--row-->\n            [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;bg-white portfolio portfolio-content classic-featured-portfolio&#8221;][vc_column][vc_row_inner el_id=&#8221;more-portfolio&#8221; el_class=&#8221;bg-white full-portfolio portfolio classic-portfolio&#8221;][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":2363,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-modernpage.php","meta":[],"_links":{"self":[{"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/pages\/3013"}],"collection":[{"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/comments?post=3013"}],"version-history":[{"count":0,"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/pages\/3013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/media\/2363"}],"wp:attachment":[{"href":"https:\/\/new.axilthemes.com\/themes\/cynic\/classic-small-digital-agency\/wp-json\/wp\/v2\/media?parent=3013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}